{"id":18196,"date":"2025-09-24T08:30:00","date_gmt":"2025-09-24T01:30:00","guid":{"rendered":"https:\/\/medicine.ku.ac.th\/kumed\/?p=18196"},"modified":"2025-09-23T18:42:42","modified_gmt":"2025-09-23T11:42:42","slug":"%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99","status":"publish","type":"post","link":"https:\/\/medicine.ku.ac.th\/kumed\/en\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/","title":{"rendered":"Mahidol Day, September 24"},"content":{"rendered":"\n<p><a href=\"https:\/\/www.facebook.com\/hashtag\/%E0%B8%A7%E0%B8%B1%E0%B8%99%E0%B8%A1%E0%B8%AB%E0%B8%B4%E0%B8%94%E0%B8%A5?__eep__=6&amp;__cft__[0]=AZW_B3yx-WfiH0AraWyCSzBY76sU_gpAgq3IqlzmEZ5Xi7z62VPCNcACv8waCBCXjrOoUgdgdWxrV0KZrQhoJeBq44L8yZqK3JwxT1YzPX9wXVzrg1QpxqOHa6zhz2qW38_3b4f0WmNb2Tz1T6bShoR4&amp;__tn__=*NK-R\" target=\"_blank\" rel=\"noreferrer noopener\">#\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25<\/a> 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 &#8220;\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22&#8221;<\/p>\n\n\n\n<p>\u0e14\u0e49\u0e27\u0e22\u0e40\u0e01\u0e25\u0e49\u0e32\u0e14\u0e49\u0e27\u0e22\u0e01\u0e23\u0e30\u0e2b\u0e21\u0e48\u0e2d\u0e21 \u0e02\u0e49\u0e32\u0e1e\u0e23\u0e30\u0e1e\u0e38\u0e17\u0e18\u0e40\u0e08\u0e49\u0e32 \u0e04\u0e13\u0e30\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e04\u0e13\u0e32\u0e08\u0e32\u0e23\u0e22\u0e4c \u0e1a\u0e38\u0e04\u0e25\u0e32\u0e01\u0e23 \u0e41\u0e25\u0e30\u0e19\u0e34\u0e2a\u0e34\u0e15 \u0e04\u0e13\u0e30\u0e41\u0e1e\u0e17\u0e22\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e40\u0e01\u0e29\u0e15\u0e23\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-uagb-image uagb-block-4c4ac6fd wp-block-uagb-image--layout-default wp-block-uagb-image--effect-static wp-block-uagb-image--align-none\"><figure class=\"wp-block-uagb-image__figure\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-1024x1024.jpg\" alt=\"\" class=\"uag-image-18197\" width=\"1024\" height=\"1024\" title=\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25\" loading=\"lazy\" role=\"img\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>#\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24<\/p>","protected":false},"author":26,"featured_media":18197,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[236],"tags":[],"class_list":["post-18196","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-faculty-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.5 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 - medicine.ku<\/title>\n<meta name=\"description\" content=\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 &quot;\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22&quot;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/medicine.ku.ac.th\/kumed\/en\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-24-\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\" \/>\n<meta property=\"og:description\" content=\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 &quot;\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/medicine.ku.ac.th\/kumed\/en\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-24-\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\/\" \/>\n<meta property=\"og:site_name\" content=\"medicine.ku\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-24T01:30:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"thitirat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"thitirat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/\"},\"author\":{\"name\":\"thitirat\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#\\\/schema\\\/person\\\/846df67ad697b6658134bed82bb2c698\"},\"headline\":\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\",\"datePublished\":\"2025-09-24T01:30:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/\"},\"wordCount\":0,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg\",\"articleSection\":[\"\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e04\u0e13\u0e30\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/\",\"name\":\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 - medicine.ku\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg\",\"datePublished\":\"2025-09-24T01:30:00+00:00\",\"description\":\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 \\\"\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\\\"\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#primaryimage\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg\",\"contentUrl\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg\",\"width\":1200,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#website\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/\",\"name\":\"medku\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#organization\",\"name\":\"medku\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/KU-thai-\u0e41\u0e1e\u0e17\u0e22\u0e4c-.png\",\"contentUrl\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/wp-content\\\/uploads\\\/2024\\\/08\\\/KU-thai-\u0e41\u0e1e\u0e17\u0e22\u0e4c-.png\",\"width\":1890,\"height\":718,\"caption\":\"medku\"},\"image\":{\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/#\\\/schema\\\/person\\\/846df67ad697b6658134bed82bb2c698\",\"name\":\"thitirat\",\"url\":\"https:\\\/\\\/medicine.ku.ac.th\\\/kumed\\\/en\\\/author\\\/thitirat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 - medicine.ku","description":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 \"\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\"","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/medicine.ku.ac.th\/kumed\/en\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-24-\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\/","og_locale":"en_US","og_type":"article","og_title":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19","og_description":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 \"\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\"","og_url":"https:\/\/medicine.ku.ac.th\/kumed\/en\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-24-\u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19\/","og_site_name":"medicine.ku","article_published_time":"2025-09-24T01:30:00+00:00","og_image":[{"width":1200,"height":1200,"url":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg","type":"image\/jpeg"}],"author":"thitirat","twitter_card":"summary_large_image","twitter_misc":{"Written by":"thitirat","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#article","isPartOf":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/"},"author":{"name":"thitirat","@id":"https:\/\/medicine.ku.ac.th\/kumed\/#\/schema\/person\/846df67ad697b6658134bed82bb2c698"},"headline":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19","datePublished":"2025-09-24T01:30:00+00:00","mainEntityOfPage":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/"},"wordCount":0,"commentCount":0,"publisher":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/#organization"},"image":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#primaryimage"},"thumbnailUrl":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg","articleSection":["\u0e02\u0e48\u0e32\u0e27\u0e2a\u0e32\u0e23\u0e04\u0e13\u0e30"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/","url":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/","name":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 - medicine.ku","isPartOf":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/#website"},"primaryImageOfPage":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#primaryimage"},"image":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#primaryimage"},"thumbnailUrl":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg","datePublished":"2025-09-24T01:30:00+00:00","description":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 \"\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\"","breadcrumb":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#primaryimage","url":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg","contentUrl":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg","width":1200,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/medicine.ku.ac.th\/kumed\/%e0%b8%a7%e0%b8%b1%e0%b8%99%e0%b8%a1%e0%b8%ab%e0%b8%b4%e0%b8%94%e0%b8%a5-24-%e0%b8%81%e0%b8%b1%e0%b8%99%e0%b8%a2%e0%b8%b2%e0%b8%a2%e0%b8%99\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/medicine.ku.ac.th\/kumed\/"},{"@type":"ListItem","position":2,"name":"\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/medicine.ku.ac.th\/kumed\/#website","url":"https:\/\/medicine.ku.ac.th\/kumed\/","name":"medku","description":"","publisher":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/medicine.ku.ac.th\/kumed\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/medicine.ku.ac.th\/kumed\/#organization","name":"medku","url":"https:\/\/medicine.ku.ac.th\/kumed\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/medicine.ku.ac.th\/kumed\/#\/schema\/logo\/image\/","url":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2024\/08\/KU-thai-\u0e41\u0e1e\u0e17\u0e22\u0e4c-.png","contentUrl":"https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2024\/08\/KU-thai-\u0e41\u0e1e\u0e17\u0e22\u0e4c-.png","width":1890,"height":718,"caption":"medku"},"image":{"@id":"https:\/\/medicine.ku.ac.th\/kumed\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/medicine.ku.ac.th\/kumed\/#\/schema\/person\/846df67ad697b6658134bed82bb2c698","name":"thitirat","url":"https:\/\/medicine.ku.ac.th\/kumed\/en\/author\/thitirat\/"}]}},"spectra_custom_meta":{"_thumbnail_id":["18197"],"_edit_lock":["1758627804:26"],"_edit_last":["26"],"\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e42\u0e1e\u0e2a\u0e15\u0e4c_fackbook_\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e48\u0e21":[""],"_\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e42\u0e1e\u0e2a\u0e15\u0e4c_fackbook_\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e48\u0e21":["field_6831151dd6359"],"\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e":[""],"_\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e23\u0e39\u0e1b\u0e20\u0e32\u0e1e":["field_683115ad4490d"],"\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e44\u0e1f\u0e25\u0e4c\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23":[""],"_\u0e25\u0e34\u0e07\u0e01\u0e4c\u0e14\u0e32\u0e27\u0e19\u0e4c\u0e42\u0e2b\u0e25\u0e14\u0e44\u0e1f\u0e25\u0e4c\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23":["field_6833288907f47"],"cmplz_hide_cookiebanner":[""],"wpr_secondary_image_id":["0"],"_ame_cpe_post_policy":["{\"accessProtection\":{\"active\":\"replace\"}}"],"_yoast_wpseo_primary_category":["236"],"_yoast_wpseo_metadesc":["\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24 \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e23\u0e48\u0e27\u0e21\u0e19\u0e49\u0e2d\u0e21\u0e23\u0e33\u0e25\u0e36\u0e01\u0e16\u0e36\u0e07\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13 \u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e34\u0e15\u0e25\u0e32\u0e18\u0e34\u0e40\u0e1a\u0e28\u0e23 \u0e2d\u0e14\u0e38\u0e25\u0e22\u0e40\u0e14\u0e0a\u0e27\u0e34\u0e01\u0e23\u0e21 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e32\u0e0a\u0e0a\u0e19\u0e01 \"\u0e1e\u0e23\u0e30\u0e1a\u0e34\u0e14\u0e32\u0e41\u0e2b\u0e48\u0e07\u0e01\u0e32\u0e23\u0e41\u0e1e\u0e17\u0e22\u0e4c\u0e41\u0e1c\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e2a\u0e38\u0e02\u0e02\u0e2d\u0e07\u0e44\u0e17\u0e22\""],"_yoast_wpseo_content_score":["90"],"_yoast_wpseo_estimated-reading-time-minutes":["1"],"custom_post_views":["<div class=\"post-views content-post post-18196 entry-meta load-static\">\r\n\t\t\t\t<span class=\"post-views-icon dashicons dashicons dashicons-groups\"><\/span> <span class=\"post-views-label\">\u0e08\u0e33\u0e19\u0e27\u0e19\u0e40\u0e02\u0e49\u0e32\u0e0a\u0e21:<\/span> <span class=\"post-views-count\">1,706<\/span>\r\n\t\t\t<\/div>"],"astra_style_timestamp_css":["1779847992"],"_cmplz_scanned_post":["1"],"_uag_css_file_name":["uag-css-18196.css"],"_uagb_previous_block_counts":["a:90:{s:21:\"uagb\/advanced-heading\";i:0;s:15:\"uagb\/blockquote\";i:0;s:12:\"uagb\/buttons\";i:0;s:18:\"uagb\/buttons-child\";i:0;s:19:\"uagb\/call-to-action\";i:0;s:15:\"uagb\/cf7-styler\";i:0;s:11:\"uagb\/column\";i:0;s:12:\"uagb\/columns\";i:0;s:14:\"uagb\/container\";i:0;s:21:\"uagb\/content-timeline\";i:0;s:27:\"uagb\/content-timeline-child\";i:0;s:14:\"uagb\/countdown\";i:0;s:12:\"uagb\/counter\";i:0;s:8:\"uagb\/faq\";i:0;s:14:\"uagb\/faq-child\";i:0;s:10:\"uagb\/forms\";i:0;s:17:\"uagb\/forms-accept\";i:0;s:19:\"uagb\/forms-checkbox\";i:0;s:15:\"uagb\/forms-date\";i:0;s:16:\"uagb\/forms-email\";i:0;s:17:\"uagb\/forms-hidden\";i:0;s:15:\"uagb\/forms-name\";i:0;s:16:\"uagb\/forms-phone\";i:0;s:16:\"uagb\/forms-radio\";i:0;s:17:\"uagb\/forms-select\";i:0;s:19:\"uagb\/forms-textarea\";i:0;s:17:\"uagb\/forms-toggle\";i:0;s:14:\"uagb\/forms-url\";i:0;s:14:\"uagb\/gf-styler\";i:0;s:15:\"uagb\/google-map\";i:0;s:11:\"uagb\/how-to\";i:0;s:16:\"uagb\/how-to-step\";i:0;s:9:\"uagb\/icon\";i:0;s:14:\"uagb\/icon-list\";i:0;s:20:\"uagb\/icon-list-child\";i:0;s:10:\"uagb\/image\";i:1;s:18:\"uagb\/image-gallery\";i:0;s:13:\"uagb\/info-box\";i:0;s:18:\"uagb\/inline-notice\";i:0;s:11:\"uagb\/lottie\";i:0;s:21:\"uagb\/marketing-button\";i:0;s:10:\"uagb\/modal\";i:0;s:18:\"uagb\/popup-builder\";i:0;s:16:\"uagb\/post-button\";i:0;s:18:\"uagb\/post-carousel\";i:0;s:17:\"uagb\/post-excerpt\";i:0;s:14:\"uagb\/post-grid\";i:0;s:15:\"uagb\/post-image\";i:0;s:17:\"uagb\/post-masonry\";i:0;s:14:\"uagb\/post-meta\";i:0;s:18:\"uagb\/post-taxonomy\";i:0;s:18:\"uagb\/post-timeline\";i:0;s:15:\"uagb\/post-title\";i:0;s:20:\"uagb\/restaurant-menu\";i:0;s:26:\"uagb\/restaurant-menu-child\";i:0;s:11:\"uagb\/review\";i:0;s:12:\"uagb\/section\";i:0;s:14:\"uagb\/separator\";i:0;s:11:\"uagb\/slider\";i:0;s:17:\"uagb\/slider-child\";i:0;s:17:\"uagb\/social-share\";i:0;s:23:\"uagb\/social-share-child\";i:0;s:16:\"uagb\/star-rating\";i:0;s:23:\"uagb\/sure-cart-checkout\";i:0;s:22:\"uagb\/sure-cart-product\";i:0;s:15:\"uagb\/sure-forms\";i:0;s:22:\"uagb\/table-of-contents\";i:0;s:9:\"uagb\/tabs\";i:0;s:15:\"uagb\/tabs-child\";i:0;s:18:\"uagb\/taxonomy-list\";i:0;s:9:\"uagb\/team\";i:0;s:16:\"uagb\/testimonial\";i:0;s:14:\"uagb\/wp-search\";i:0;s:19:\"uagb\/instagram-feed\";i:0;s:10:\"uagb\/login\";i:0;s:17:\"uagb\/loop-builder\";i:0;s:18:\"uagb\/loop-category\";i:0;s:20:\"uagb\/loop-pagination\";i:0;s:15:\"uagb\/loop-reset\";i:0;s:16:\"uagb\/loop-search\";i:0;s:14:\"uagb\/loop-sort\";i:0;s:17:\"uagb\/loop-wrapper\";i:0;s:13:\"uagb\/register\";i:0;s:19:\"uagb\/register-email\";i:0;s:24:\"uagb\/register-first-name\";i:0;s:23:\"uagb\/register-last-name\";i:0;s:22:\"uagb\/register-password\";i:0;s:30:\"uagb\/register-reenter-password\";i:0;s:19:\"uagb\/register-terms\";i:0;s:22:\"uagb\/register-username\";i:0;}"],"_uagb_last_spectra_edit":["1776768045"],"_elementor_page_assets":["a:0:{}"],"_uag_page_assets":["a:9:{s:3:\"css\";s:7133:\".wp-block-uagb-image{display:flex}.wp-block-uagb-image__figure{position:relative;display:flex;flex-direction:column;max-width:100%;height:auto;margin:0}.wp-block-uagb-image__figure img{height:auto;display:flex;max-width:100%;transition:box-shadow .2s ease}.wp-block-uagb-image__figure>a{display:inline-block}.wp-block-uagb-image__figure figcaption{text-align:center;margin-top:.5em;margin-bottom:1em}.wp-block-uagb-image .components-placeholder.block-editor-media-placeholder .components-placeholder__instructions{align-self:center}.wp-block-uagb-image--align-left{text-align:left}.wp-block-uagb-image--align-right{text-align:right}.wp-block-uagb-image--align-center{text-align:center}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure{margin-left:calc(50% - 50vw);margin-right:calc(50% - 50vw);max-width:100vw;width:100vw;height:auto}.wp-block-uagb-image--align-full .wp-block-uagb-image__figure img{height:auto;width:100% !important}.wp-block-uagb-image--align-wide .wp-block-uagb-image__figure img{height:auto;width:100%}.wp-block-uagb-image--layout-overlay__color-wrapper{position:absolute;left:0;top:0;right:0;bottom:0;opacity:.2;background:rgba(0,0,0,.5);transition:opacity .35s ease-in-out}.wp-block-uagb-image--layout-overlay-link{position:absolute;left:0;right:0;bottom:0;top:0}.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity:1}.wp-block-uagb-image--layout-overlay__inner{position:absolute;left:15px;right:15px;bottom:15px;top:15px;display:flex;align-items:center;justify-content:center;flex-direction:column;border-color:#fff;transition:.35s ease-in-out}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.top-center,.wp-block-uagb-image--layout-overlay__inner.top-right{justify-content:flex-start}.wp-block-uagb-image--layout-overlay__inner.bottom-left,.wp-block-uagb-image--layout-overlay__inner.bottom-center,.wp-block-uagb-image--layout-overlay__inner.bottom-right{justify-content:flex-end}.wp-block-uagb-image--layout-overlay__inner.top-left,.wp-block-uagb-image--layout-overlay__inner.center-left,.wp-block-uagb-image--layout-overlay__inner.bottom-left{align-items:flex-start}.wp-block-uagb-image--layout-overlay__inner.top-right,.wp-block-uagb-image--layout-overlay__inner.center-right,.wp-block-uagb-image--layout-overlay__inner.bottom-right{align-items:flex-end}.wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{color:#fff;transition:transform .35s,opacity .35s ease-in-out;transform:translate3d(0, 24px, 0);margin:0;line-height:1em}.wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width:30%;border-top-width:2px;border-top-color:#fff;border-top-style:solid;margin-bottom:10px;opacity:0;transition:transform .4s,opacity .4s ease-in-out;transform:translate3d(0, 30px, 0)}.wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity:0;overflow:visible;color:#fff;transition:transform .45s,opacity .45s ease-in-out;transform:translate3d(0, 35px, 0)}.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-heading,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-separator,.wp-block-uagb-image--layout-overlay__inner:hover .uagb-image-caption{opacity:1;transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-zoomin .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:scale(1.05)}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure .wp-block-uagb-image--layout-overlay__color-wrapper{width:calc(100% + 40px) !important;max-width:none !important;transform:translate3d(-40px, 0, 0);transition:transform .35s ease-in-out}.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover img,.wp-block-uagb-image--effect-slide .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{transform:translate3d(0, 0, 0)}.wp-block-uagb-image--effect-grayscale img{filter:grayscale(0%);transition:.35s ease-in-out}.wp-block-uagb-image--effect-grayscale:hover img{filter:grayscale(100%)}.wp-block-uagb-image--effect-blur img{filter:blur(0);transition:.35s ease-in-out}.wp-block-uagb-image--effect-blur:hover img{filter:blur(3px)}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-default figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure figcaption{font-style: normal;align-self: center;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay figure img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 0.2;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner{left: 15px;right: 15px;top: 15px;bottom: 15px;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading{font-style: normal;color: #fff;opacity: 1;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-heading a{color: #fff;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 0;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__color-wrapper{opacity: 1;}.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{width: 30%;border-top-width: 2px;border-top-color: #fff;opacity: 0;}.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-caption{opacity: 1;}.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure:hover .wp-block-uagb-image--layout-overlay__inner .uagb-image-separator{opacity: 1;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-default figure:hover img{box-shadow: 0px 0px 0 #00000070;}.uagb-block-4c4ac6fd.wp-block-uagb-image--layout-overlay figure:hover img{box-shadow: 0px 0px 0 #00000070;}@media only screen and (max-width: 976px) {.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}@media only screen and (max-width: 767px) {.uagb-block-4c4ac6fd.wp-block-uagb-image .wp-block-uagb-image__figure img{width: px;height: auto;}}.uag-blocks-common-selector{z-index:var(--z-index-desktop) !important}@media(max-width: 976px){.uag-blocks-common-selector{z-index:var(--z-index-tablet) !important}}@media(max-width: 767px){.uag-blocks-common-selector{z-index:var(--z-index-mobile) !important}}\";s:2:\"js\";s:0:\"\";s:18:\"current_block_list\";a:9:{i:0;s:14:\"core\/paragraph\";i:1;s:10:\"uagb\/image\";i:2;s:11:\"core\/search\";i:3;s:10:\"core\/group\";i:4;s:12:\"core\/heading\";i:5;s:17:\"core\/latest-posts\";i:6;s:20:\"core\/latest-comments\";i:7;s:13:\"core\/archives\";i:8;s:15:\"core\/categories\";}s:8:\"uag_flag\";b:1;s:11:\"uag_version\";s:10:\"1788327117\";s:6:\"gfonts\";a:0:{}s:10:\"gfonts_url\";s:0:\"\";s:12:\"gfonts_files\";a:0:{}s:14:\"uag_faq_layout\";b:0;}"]},"uagb_featured_image_src":{"full":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg",1200,1200,false],"thumbnail":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-150x150.jpg",150,150,true],"medium":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-500x500.jpg",500,500,true],"medium_large":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-768x768.jpg",768,768,true],"large":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg",1200,1200,false],"2048x2048":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25.jpg",1200,1200,false],"trp-custom-language-flag":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-12x12.jpg",12,12,true],"custom-500x500":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-500x500.jpg",500,500,true],"custom-500x380":["https:\/\/medicine.ku.ac.th\/kumed\/wp-content\/uploads\/2025\/09\/\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25-500x380.jpg",500,380,true]},"uagb_author_info":{"display_name":"thitirat","author_link":"https:\/\/medicine.ku.ac.th\/kumed\/en\/author\/thitirat\/"},"uagb_comment_info":0,"uagb_excerpt":"#\u0e27\u0e31\u0e19\u0e21\u0e2b\u0e34\u0e14\u0e25 24","_links":{"self":[{"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/posts\/18196","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/comments?post=18196"}],"version-history":[{"count":1,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/posts\/18196\/revisions"}],"predecessor-version":[{"id":18198,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/posts\/18196\/revisions\/18198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/media\/18197"}],"wp:attachment":[{"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/media?parent=18196"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/categories?post=18196"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/medicine.ku.ac.th\/kumed\/en\/wp-json\/wp\/v2\/tags?post=18196"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}